{"id":1232,"date":"2020-12-17T13:32:55","date_gmt":"2020-12-17T12:32:55","guid":{"rendered":"https:\/\/www.hansemondial.de\/blog\/?p=1232"},"modified":"2020-12-17T15:11:44","modified_gmt":"2020-12-17T14:11:44","slug":"jahresrueckblick-2020","status":"publish","type":"post","link":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/","title":{"rendered":"Jahresr\u00fcckblick 2020"},"content":{"rendered":"\n<p>Ein herausforderndes und sehr spannendes Jahr neigt sich dem Ende zu. Wir m\u00f6chten mit euch gemeinsam das Jahr 2020 Revue passieren lassen und unsere pers\u00f6nlichen Highlights der einzelnen Monate vorstellen. <br>Wir freuen uns bereits auf das n\u00e4chste Jahr und alle damit verbundenen Projekte, Herausforderungen und Abenteuer. 2021 &#8211; wir sind bereit!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">JANUAR<\/h3>\n\n\n\n<p>Neben einem Teamzuwachs von vier neuen Teammitgliedern im Bereich Vertrieb, Einkauf und Marketing wartete bereits ein Meilenstein Mitte Januar auf uns: die <a href=\"https:\/\/www.boe-messe.de\/startseite\/\" target=\"_blank\" rel=\"noreferrer noopener\">BOE INTERNATIONAL<\/a> Messe in Dortmund. Mit dem halben Team von <a href=\"https:\/\/www.hansemondial.de\/de\/bustalk-live\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hanse Mondial<\/a> waren wir vor Ort und haben wertvolle Kontakte aus der Eventbranche gekn\u00fcpft. Es waren zwei Tage voller guter Laune, passender Musik von DJ Aron Kent und leckeren Gin Tonics. Wir freuen uns bereits auf  die BOE im Juni 2021 und k\u00f6nnen es kaum erwarten wieder dabei zu sein!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">FEBRUAR<\/h3>\n\n\n\n<p>Im Februar folgte bereits ein weiteres Highlight. Wir waren f\u00fcr einen unserer Gro\u00dfkunden in D\u00fcsseldorf im Rahmen der <a href=\"https:\/\/www.euroshop.de\" target=\"_blank\" rel=\"noreferrer noopener\">EuroShop Messe<\/a> im Einsatz. Eine knappe Woche haben wir die Teilnehmer den ganzen Tag zwischen dem D\u00fcsseldorfer Flughafen, verschiedenen Hotels und dem Messegel\u00e4nde mit Hilfe unserer tollen <a href=\"https:\/\/www.hansemondial.de\/de\/netzwerk\/\" target=\"_blank\" rel=\"noreferrer noopener\">Netzwerkpartnern<\/a> sicher transportiert. Das Team hat vor Ort flei\u00dfig koordiniert, damit alles reibungslos ablaufen konnte. Das war eine spannende Abwechslung!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00c4RZ<\/h3>\n\n\n\n<p>Auch wenn es im M\u00e4rz anders kam als geplant, haben wir mit unserem Team definitiv das Beste aus der Situation gemacht. Bereits Anfang M\u00e4rz wurde das gesamte Team ins Homeoffice geschickt und hat von zu Hause aus weiterhin an bevorstehenden Projekten gearbeitet. Ebenfalls haben wir die Zeit f\u00fcr die Verbesserung unserer Strukturen und Prozesse genutzt, wovon wir bereits heute profitieren. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">APRIL<\/h3>\n\n\n\n<p>Wir waren weiterhin im Homeoffice und im Hintergrund wurde unser B\u00fcroumzug in die Hamburger Innenstadt geplant. Durch den stetigen Teamzuwachs war uns bereits seit mehreren Monaten klar, dass wir ein gr\u00f6\u00dferes B\u00fcro ben\u00f6tigten. Unsere neue Fl\u00e4che in Hammerbrook ist wie f\u00fcr uns gemacht und wir f\u00fchlen uns dort sehr wohl. Bei der B\u00fcroausstattung hatten wir tatkr\u00e4ftige Unterst\u00fctzung von <a href=\"https:\/\/wema-raumkonzepte.de\" target=\"_blank\" rel=\"noreferrer noopener\">WEMA RaumKonzepte<\/a> aus L\u00fcneburg, die uns ebenfalls sehr bei unserem Umzug unter die Arme gegriffen haben &#8211; herzlichen Dank an dieser Stelle! <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">MAI<\/h3>\n\n\n\n<p>Langsam kehrte etwas Alltag ein und wir waren \u00fcberwiegend wieder in unseren neuen B\u00fcror\u00e4umen &#8211; definitiv sch\u00f6ner als im Homeoffice. Trotzdem hatte die Busbranche immer noch mit den Folgen durch Corona zu k\u00e4mpfen. In unserem w\u00f6chentlichen digitalen Branchenstammtisch, dem <a href=\"https:\/\/www.hansemondial.de\/de\/bustalk-live\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bustalk Live<\/a>, entstand bereits im April die Idee einer Busdemonstration in Hamburg. Gesagt, getan! Wir steckten viel Zeit in die Vorbereitung und waren mehr als dankbar, dass \u00fcber 150 Reisebusse am 07. Mai 2020 die Binnenalster in Hamburg hupend umrundeten. Der Zuspruch der Busunternehmer motivierte uns sehr und wir sind bis heute sehr dankbar f\u00fcr das entgegengebrachte Vertrauen.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"olsen-light-responsive-embed\"><iframe loading=\"lazy\" title=\"#busretten - Bus Demo in Hamburg am 07.05.2020\" width=\"665\" height=\"374\" src=\"https:\/\/www.youtube.com\/embed\/47wmREDi8SA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption><a href=\"Busdemonstration in Hamburg mit rund 150 Reisebussen.\" target=\"_blank\" rel=\"noreferrer noopener\">#busretten: Busdemonstration in Hamburg mit rund 150 Reisebussen.<\/a><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">JUNI<\/h3>\n\n\n\n<p>Der Busdemonstration in Hamburg folgten viele weitere Demonstrationen und bundesweite Aktionstage. Das Highlight im Juni war definitiv der bundesweite Aktionstag in der Hauptstadt Berlin. Gemeinsam mit den Verb\u00e4nden und Busunternehmern haben wir ein Zeichen f\u00fcr die Busbranche gesetzt. Wir haben auf die missliche Lage aufmerksam gemacht und das mit Erfolg! Die Politik hatte die Busbranche geh\u00f6rt und weitere finanzielle Hilfe in Aussicht gestellt. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">JULI<\/h3>\n\n\n\n<p>Langsam aber sicher kehrte immer mehr Normalit\u00e4t in unseren Alltag und wir waren mehr als froh, dass wir unseren ersten <a href=\"https:\/\/www.hansemondial.de\/de\/bustalk-live\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bustalk Live<\/a> in Hamburg erfolgreich umsetzen konnten. Gemeinsam mit rund 15 Busunternehmern entwickelten wir neue Ideen und Ans\u00e4tze f\u00fcr die Busbranche. Wir freuen uns bereits auf den n\u00e4chsten Bustalk Live in unseren B\u00fcror\u00e4umen im n\u00e4chsten Jahr! <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">AUGUST<\/h3>\n\n\n\n<p>Im August ging es weiter im Tagesgesch\u00e4ft und wir waren dankbar daf\u00fcr, dass die Reisebusse weiterhin rollen durften. F\u00fcr das Durchhalteverm\u00f6gen wurde das Team mit einem sch\u00f6nen Teamtag belohnt, den wir in der Golf Lounge Hamburg verbracht haben. So konnte jeder mal etwas vom Alltagsgeschehen abschalten und gleichzeitig waren wir dankbar f\u00fcr einen tollen Teamtag!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SEPTEMBER<\/h3>\n\n\n\n<p>Am 19. September stand eine ganz besondere Aktivit\u00e4t in unserem Kalender:<a href=\"https:\/\/www.youtube.com\/watch?v=TztIxUqYSmY&amp;feature=youtu.be\" target=\"_blank\" rel=\"noreferrer noopener\"> der World Cleanup Day<\/a>. Gemeinsam mit unseren Partnern, dem Harburg-Huus und der Stiftung Pfoten und Meer, haben wir anl\u00e4sslich des World Cleanup Days uns f\u00fcr eine saubere Umwelt eingesetzt. Mit dem Reisebus ging es an den Hamburger Elbstrand, an dem wir gemeinsam M\u00fcll sammelten. Ein toller Tag und wir freuen uns bereits auch im n\u00e4chsten Jahr Teil des World Cleanup Days zu sein. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">OKTOBER<\/h3>\n\n\n\n<p>Weiter ging es mit einem weiteren Highlight im Bereich Nachhaltigkeit. Schon seit Beginn von Hanse Mondial spielt das Thema Nachhaltigkeit eine wichtige Rolle f\u00fcr uns. Daher wurden wir im Oktober mit der UmweltPartnerschaft Hamburg der Umweltbeh\u00f6rde ausgezeichnet, worauf wir sehr stolz sind. Die Urkunde motiviert uns nat\u00fcrlich weiter an unserer Nachhaltigkeit zu arbeiten und diese stetig zu verbessern.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">NOVEMBER<\/h3>\n\n\n\n<p>Der November stand ganz im Zeichen der Digitalisierung, denn unser Hanse MMS (Mobility Management Software) wurde bei immer mehr Projekten erfolgreich eingesetzt. Mit unserem MMS, dem digitalen Kontrollzentrum, bieten wir unseren Kunden eine individuelle und transparente Mobilit\u00e4tsl\u00f6sung f\u00fcr Reisebusse an. In seiner Grundfunktion k\u00f6nnen unsere Kunden die Auslastung, P\u00fcnktlichkeit und Effizienz ihrer Shuttles dokumentieren und optimieren.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"olsen-light-responsive-embed\"><iframe loading=\"lazy\" title=\"Hanse Mondial GmbH - Mobility Management Software\" width=\"665\" height=\"374\" src=\"https:\/\/www.youtube.com\/embed\/bt7CJeIGBJs?start=1&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption><a href=\"https:\/\/www.youtube.com\/watch?v=bt7CJeIGBJs&amp;t=1s\" target=\"_blank\" rel=\"noreferrer noopener\">Unsere Mobility Management Software.<\/a><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">DEZEMBER<\/h3>\n\n\n\n<p>Es weihnachtet sehr! Nicht nur unser gesamtes Team freut sich bereits auf besinnliche Feiertage. Auch unser Hanse Mondial Adventskalender mit der dazugeh\u00f6rigen Spendenkampagne f\u00fcr die teilnehmenden Organisationen sto\u00df auf sehr positive Resonanz. Wir freuen uns bereits auf die gemeinsamen Aktionen mit den Organisationen in 2021!<\/p>\n\n\n\n<p>Auch wenn 2020 etwas anders gelaufen ist als geplant, ziehen wir eine positive Resonanz aus dem Jahr 2020 und freuen uns bereits auf viele, neue Meilensteine in 2021! Wir w\u00fcnschen euch besinnliche Feiertage und einen guten Rutsch ins neue Jahr. Bleibt gesund! <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-handler-einbetten wp-block-embed-handler-einbetten wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"olsen-light-responsive-embed\"><iframe loading=\"lazy\" title=\"Weihnachtsgr\u00fc\u00dfe von Hanse Mondial\" width=\"665\" height=\"374\" src=\"https:\/\/www.youtube.com\/embed\/X6Mff92bD4Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ein herausforderndes und sehr spannendes Jahr neigt sich dem Ende zu. Wir m\u00f6chten mit euch gemeinsam das Jahr 2020 Revue passieren lassen und unsere pers\u00f6nlichen Highlights der einzelnen Monate vorstellen. Wir freuen uns bereits auf [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[139,60,140,141,138],"class_list":["post-1232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hanse-mondial-insights","tag-139","tag-hanse-mondial-insights","tag-jahresrueckblick","tag-meilensteine","tag-rueckblick"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jahresr\u00fcckblick 2020 - Hanse Mondial Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jahresr\u00fcckblick 2020 - Hanse Mondial Blog\" \/>\n<meta property=\"og:description\" content=\"Ein herausforderndes und sehr spannendes Jahr neigt sich dem Ende zu. Wir m\u00f6chten mit euch gemeinsam das Jahr 2020 Revue passieren lassen und unsere pers\u00f6nlichen Highlights der einzelnen Monate vorstellen. Wir freuen uns bereits auf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanse Mondial Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HanseMondial\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-17T12:32:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-17T14:11:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tim Derix\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tim Derix\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/\"},\"author\":{\"name\":\"Tim Derix\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#\/schema\/person\/d8bfbb02246adfe2a289d6bf40ead0e3\"},\"headline\":\"Jahresr\u00fcckblick 2020\",\"datePublished\":\"2020-12-17T12:32:55+00:00\",\"dateModified\":\"2020-12-17T14:11:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/\"},\"wordCount\":986,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png\",\"keywords\":[\"2020\",\"Hanse Mondial Insights\",\"Jahresr\u00fcckblick\",\"Meilensteine\",\"R\u00fcckblick\"],\"articleSection\":[\"Hanse Mondial Insights\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/\",\"url\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/\",\"name\":\"Jahresr\u00fcckblick 2020 - Hanse Mondial Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png\",\"datePublished\":\"2020-12-17T12:32:55+00:00\",\"dateModified\":\"2020-12-17T14:11:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage\",\"url\":\"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png\",\"contentUrl\":\"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png\",\"width\":720,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.hansemondial.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jahresr\u00fcckblick 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#website\",\"url\":\"https:\/\/www.hansemondial.de\/blog\/\",\"name\":\"Hanse Mondial Blog\",\"description\":\"Der Buslogistik Blog\",\"publisher\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hansemondial.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#organization\",\"name\":\"Hanse Mondial GmbH\",\"url\":\"https:\/\/www.hansemondial.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2023\/06\/MicrosoftTeams-image-5.png\",\"contentUrl\":\"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2023\/06\/MicrosoftTeams-image-5.png\",\"width\":300,\"height\":150,\"caption\":\"Hanse Mondial GmbH\"},\"image\":{\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/HanseMondial\/\",\"https:\/\/www.instagram.com\/hansemondial_buslogistik\/\",\"https:\/\/sv.linkedin.com\/company\/hanse-mondial-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCsvt7IF3WGv6rWNXykzugHA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#\/schema\/person\/d8bfbb02246adfe2a289d6bf40ead0e3\",\"name\":\"Tim Derix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.hansemondial.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ffcef1b65ae567f54b83e4e40171ae5cc4d36dad47078c89fe88308a4425b688?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ffcef1b65ae567f54b83e4e40171ae5cc4d36dad47078c89fe88308a4425b688?s=96&d=mm&r=g\",\"caption\":\"Tim Derix\"},\"url\":\"https:\/\/www.hansemondial.de\/blog\/author\/tderix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jahresr\u00fcckblick 2020 - Hanse Mondial Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/","og_locale":"de_DE","og_type":"article","og_title":"Jahresr\u00fcckblick 2020 - Hanse Mondial Blog","og_description":"Ein herausforderndes und sehr spannendes Jahr neigt sich dem Ende zu. Wir m\u00f6chten mit euch gemeinsam das Jahr 2020 Revue passieren lassen und unsere pers\u00f6nlichen Highlights der einzelnen Monate vorstellen. Wir freuen uns bereits auf [&hellip;]","og_url":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/","og_site_name":"Hanse Mondial Blog","article_publisher":"https:\/\/www.facebook.com\/HanseMondial\/","article_published_time":"2020-12-17T12:32:55+00:00","article_modified_time":"2020-12-17T14:11:44+00:00","og_image":[{"width":720,"height":471,"url":"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png","type":"image\/png"}],"author":"Tim Derix","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tim Derix","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#article","isPartOf":{"@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/"},"author":{"name":"Tim Derix","@id":"https:\/\/www.hansemondial.de\/blog\/#\/schema\/person\/d8bfbb02246adfe2a289d6bf40ead0e3"},"headline":"Jahresr\u00fcckblick 2020","datePublished":"2020-12-17T12:32:55+00:00","dateModified":"2020-12-17T14:11:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/"},"wordCount":986,"commentCount":1,"publisher":{"@id":"https:\/\/www.hansemondial.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png","keywords":["2020","Hanse Mondial Insights","Jahresr\u00fcckblick","Meilensteine","R\u00fcckblick"],"articleSection":["Hanse Mondial Insights"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/","url":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/","name":"Jahresr\u00fcckblick 2020 - Hanse Mondial Blog","isPartOf":{"@id":"https:\/\/www.hansemondial.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png","datePublished":"2020-12-17T12:32:55+00:00","dateModified":"2020-12-17T14:11:44+00:00","breadcrumb":{"@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#primaryimage","url":"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png","contentUrl":"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2020\/12\/Design-ohne-Titel.png","width":720,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/www.hansemondial.de\/blog\/jahresrueckblick-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.hansemondial.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Jahresr\u00fcckblick 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.hansemondial.de\/blog\/#website","url":"https:\/\/www.hansemondial.de\/blog\/","name":"Hanse Mondial Blog","description":"Der Buslogistik Blog","publisher":{"@id":"https:\/\/www.hansemondial.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hansemondial.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.hansemondial.de\/blog\/#organization","name":"Hanse Mondial GmbH","url":"https:\/\/www.hansemondial.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hansemondial.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2023\/06\/MicrosoftTeams-image-5.png","contentUrl":"https:\/\/www.hansemondial.de\/blog\/wp-content\/uploads\/2023\/06\/MicrosoftTeams-image-5.png","width":300,"height":150,"caption":"Hanse Mondial GmbH"},"image":{"@id":"https:\/\/www.hansemondial.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HanseMondial\/","https:\/\/www.instagram.com\/hansemondial_buslogistik\/","https:\/\/sv.linkedin.com\/company\/hanse-mondial-gmbh","https:\/\/www.youtube.com\/channel\/UCsvt7IF3WGv6rWNXykzugHA"]},{"@type":"Person","@id":"https:\/\/www.hansemondial.de\/blog\/#\/schema\/person\/d8bfbb02246adfe2a289d6bf40ead0e3","name":"Tim Derix","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hansemondial.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ffcef1b65ae567f54b83e4e40171ae5cc4d36dad47078c89fe88308a4425b688?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ffcef1b65ae567f54b83e4e40171ae5cc4d36dad47078c89fe88308a4425b688?s=96&d=mm&r=g","caption":"Tim Derix"},"url":"https:\/\/www.hansemondial.de\/blog\/author\/tderix\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/posts\/1232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/comments?post=1232"}],"version-history":[{"count":11,"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/posts\/1232\/revisions"}],"predecessor-version":[{"id":1252,"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/posts\/1232\/revisions\/1252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/media\/1233"}],"wp:attachment":[{"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/media?parent=1232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/categories?post=1232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hansemondial.de\/blog\/wp-json\/wp\/v2\/tags?post=1232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}